{"id":306,"count":15,"description":"","link":"https:\/\/www.synergita.com\/blog\/tag\/objectives-and-key-results\/","name":"Objectives and Key Results","slug":"objectives-and-key-results","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Objectives and Key Results Archives - Blogs | Resources<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Objectives and Key Results Archives - Blogs | Resources\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.synergita.com\/blog\/tag\/objectives-and-key-results\/\" \/>\n<meta property=\"og:site_name\" content=\"Blogs | Resources\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.synergita.com\/blog\/tag\/objectives-and-key-results\/\",\"url\":\"https:\/\/www.synergita.com\/blog\/tag\/objectives-and-key-results\/\",\"name\":\"Objectives and Key Results Archives - Blogs | Resources\",\"isPartOf\":{\"@id\":\"https:\/\/www.synergita.com\/blog\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.synergita.com\/blog\/tag\/objectives-and-key-results\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.synergita.com\/blog\/tag\/objectives-and-key-results\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.synergita.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Objectives and Key Results\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.synergita.com\/blog\/#website\",\"url\":\"https:\/\/www.synergita.com\/blog\/\",\"name\":\"Blogs | Resources\",\"description\":\"Synergita\",\"publisher\":{\"@id\":\"https:\/\/www.synergita.com\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.synergita.com\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.synergita.com\/blog\/#organization\",\"name\":\"Blogs | Resources\",\"url\":\"https:\/\/www.synergita.com\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.synergita.com\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.synergita.com\/blog\/wp-content\/uploads\/2024\/05\/synergita-logo-white.png\",\"contentUrl\":\"https:\/\/www.synergita.com\/blog\/wp-content\/uploads\/2024\/05\/synergita-logo-white.png\",\"width\":95,\"height\":40,\"caption\":\"Blogs | Resources\"},\"image\":{\"@id\":\"https:\/\/www.synergita.com\/blog\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Objectives and Key Results Archives - Blogs | Resources","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"Objectives and Key Results Archives - Blogs | Resources","og_url":"https:\/\/www.synergita.com\/blog\/tag\/objectives-and-key-results\/","og_site_name":"Blogs | Resources","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.synergita.com\/blog\/tag\/objectives-and-key-results\/","url":"https:\/\/www.synergita.com\/blog\/tag\/objectives-and-key-results\/","name":"Objectives and Key Results Archives - Blogs | Resources","isPartOf":{"@id":"https:\/\/www.synergita.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.synergita.com\/blog\/tag\/objectives-and-key-results\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.synergita.com\/blog\/tag\/objectives-and-key-results\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.synergita.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Objectives and Key Results"}]},{"@type":"WebSite","@id":"https:\/\/www.synergita.com\/blog\/#website","url":"https:\/\/www.synergita.com\/blog\/","name":"Blogs | Resources","description":"Synergita","publisher":{"@id":"https:\/\/www.synergita.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.synergita.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.synergita.com\/blog\/#organization","name":"Blogs | Resources","url":"https:\/\/www.synergita.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.synergita.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.synergita.com\/blog\/wp-content\/uploads\/2024\/05\/synergita-logo-white.png","contentUrl":"https:\/\/www.synergita.com\/blog\/wp-content\/uploads\/2024\/05\/synergita-logo-white.png","width":95,"height":40,"caption":"Blogs | Resources"},"image":{"@id":"https:\/\/www.synergita.com\/blog\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.synergita.com\/blog\/wp-json\/wp\/v2\/tags\/306","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.synergita.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.synergita.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.synergita.com\/blog\/wp-json\/wp\/v2\/posts?tags=306"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}